{"id":159,"date":"2016-02-02T13:51:18","date_gmt":"2016-02-02T12:51:18","guid":{"rendered":"http:\/\/www.diesichtderdinge.de\/?page_id=159"},"modified":"2016-09-17T20:52:46","modified_gmt":"2016-09-17T18:52:46","slug":"gesichter","status":"publish","type":"page","link":"https:\/\/www.diesichtderdinge.de\/en\/fotografie\/portfolio\/gesichter\/","title":{"rendered":"FACES"},"content":{"rendered":"<p><img decoding=\"async\" class=\"ngg_displayed_gallery mceItem\" src=\"http:\/\/www.diesichtderdinge.de\/nextgen-attach_to_post\/preview\/id--638\" alt=\"\" data-mce-placeholder=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":152,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-159","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/pages\/159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/comments?post=159"}],"version-history":[{"count":6,"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/pages\/159\/revisions"}],"predecessor-version":[{"id":1582,"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/pages\/159\/revisions\/1582"}],"up":[{"embeddable":true,"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/pages\/152"}],"wp:attachment":[{"href":"https:\/\/www.diesichtderdinge.de\/en\/wp-json\/wp\/v2\/media?parent=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}